{"id":14556,"date":"2026-02-26T04:38:01","date_gmt":"2026-02-26T03:38:01","guid":{"rendered":"https:\/\/rowermax.shop\/ro64\/produkt\/lekki-rower-dla-dziecka-woom-go-2-14-metallic-blue-niebieski\/"},"modified":"2026-02-26T04:38:02","modified_gmt":"2026-02-26T03:38:02","slug":"lekki-rower-dla-dziecka-woom-go-2-14-metallic-blue-niebieski","status":"publish","type":"product","link":"https:\/\/velravo.shop\/ro64\/produkt\/lekki-rower-dla-dziecka-woom-go-2-14-metallic-blue-niebieski\/","title":{"rendered":"Lekki Rower dla dziecka Woom GO 2 14&quot; Metallic Blue\/Niebieski"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">ROWER DLA DZIECI WOOM GO 2<\/h3>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Ultralekki rower na 14&#8243; ko\u0142ach stworzony z my\u015bl\u0105 o pierwszych, bezpiecznych obrotach peda\u0142ami, przeznaczony dla dzieci w wieku 3 lat i starszych.<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Rozmiar:&nbsp;<b>14&#8243;<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Waga:&nbsp;<b>5 kg<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wiek:&nbsp;<b>3 &#8211; 4.5 lat<\/b><\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wzrost:&nbsp;<b>95\u2013110 cm<\/b><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany\" srcset=\"https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 360w,https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 720w,https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1024w,https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1440w,https:\/\/a.allegroimg.com\/original\/11aa2f\/078ddc32474eb3fc079163ebfb05\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Stopien-zlozenia-wstepnie-zlozony-wyregulowany 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Stopie\u0144 z\u0142o\u017cenia wst\u0119pnie z\u0142o\u017cony, wyregulowany\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rower woom GO 2<\/b><\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Nadchodzi magiczny moment!<\/b><\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zobacz na w\u0142asne oczy jak Twoje dziecko po raz pierwszy rusza, samodzielnie peda\u0142uj\u0105c. To istny cud! Zobacz w jego oczach poczucie wolno\u015bci i rado\u015b\u0107 z pokonania ogranicze\u0144!&nbsp;woom&nbsp;GO 2 da poczucie pewno\u015bci siebie i lekko\u015bci przemieszczania si\u0119 o w\u0142asnych si\u0142ach. Ten wyj\u0105tkowy moment w \u017cyciu Twojego dziecka b\u0119dzie naprawd\u0119 magiczny.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Najwa\u017cniejsze cechy:<\/b>&nbsp;tylny hamulec oznaczony na zielono, stabilizator kierownicy, ergonomiczne siode\u0142ko, uchwyty dopasowane do wielko\u015bci d\u0142oni dziecka i zako\u0144czone pier\u015bcieniami bezpiecze\u0144stwa, a wszystko to wyprodukowane bez toksycznych substancji. Kierownica w stylu BMX i zwarta os\u0142ona \u0142a\u0144cucha dope\u0142niaj\u0105 ca\u0142o\u015bci.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">A Tyre\/wheel size14\u201d<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">B Cockpit\/handlebar height 628 mm (22.7\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">C Steering angle68\u00ba<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">D Horizontal top tube length 360.5 mm (14.2\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">E Wheelbase641 mm (25.2\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">F Seat tube angle68\u00ba<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">G Min. saddle height394 mm (15.5\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">H Max. saddle height489 mm (19.3\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">I Crank arm length80 mm (3.2\u201d)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">J Handlebar adjustment+\/-10\u00b0<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">K Stand-over height 350 mm (13.8\u201d)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">woom GO 2 <b>&#8211; Najwa\u017cniejsze funkcje<\/b><\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Sprytna rama<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wykonana z aluminum rama tego roweru jest nie tylko superlekka, woom zadba\u0142 o takie ustawienie kierownicy i siode\u0142ka, kt\u00f3re uwzgl\u0119dnia wzrost i poziom rozwoju psychomotorycznego dziecka. Mo\u017ce ono wygodnie usi\u0105\u015b\u0107, wyprostowa\u0107 si\u0119, ale co wa\u017cniejsze, geometria ramy u\u0142atwia mu peda\u0142owanie i zapewnia szerokie pole obserwacji. Du\u017cy rozstaw osi wraz z \u0142agodnym k\u0105tem g\u0142\u00f3wki s\u0105 gwarancj\u0105 stabilno\u015bci i bezpiecze\u0144stwa nawet w trakcie rowerowych szale\u0144stw.<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Dzieci\u0119cy hamulec r\u0119czny<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Twoje dziecko od razu rozpozna hamulec tylny, poniewa\u017c klamka jest zielona. Identyfikacja kolorystyczna zapobiega pomyleniu hamulc\u00f3w przedniego z tylnym, co zwi\u0119ksza bezpiecze\u0144stwo jazdy. Nasza specjalnie zaprojektowana klamka hamulca jest \u0142atwa do naci\u015bni\u0119cia ma\u0142ymi d\u0142o\u0144mi i wymaga minimalnej si\u0142y, by bezpiecznie zatrzyma\u0107 rower. Hamowanie nie mog\u0142o by\u0107 prostsze.<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Elastyczny stabilizator kierownicy<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Nasz specjalnie opracowany stabilizator kierownicy to bardzo sprytny element zwi\u0119kszaj\u0105cy bezpiecze\u0144stwo. Stabilizuje kierowanie rowerkiem i zapobiega wypadkom, kt\u00f3re mog\u0142yby wynikn\u0105\u0107 ze zbytniego skr\u0119cenia kierownicy &#8211; cz\u0119stej sytuacji przy ma\u0142ych pr\u0119dko\u015bciach oraz intensywnych interakcjach przy piaskownicy.<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Uchwyty z ochraniaczem<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">S\u0105 najcie\u0144sze w swojej klasie i dlatego, tak\u017ce ma\u0142a d\u0142o\u0144 mo\u017ce je bezpiecznie uchwyci\u0107. M\u00f3wi\u0105c o bezpiecze\u0144stwie mamy na my\u015bli wysokiej klasy, przyczepne materia\u0142y bez toksycznych substancji, \u015brubki zabezpieczaj\u0105ce przed przekr\u0119ceniem si\u0119 oraz specjalne os\u0142ony chroni\u0105ce d\u0142o\u0144 przed uderzeniem, w przypadku wywrotki, a nawet zsuni\u0119ciem si\u0119 z kierownicy.<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Ergonomiczne siod\u0142o<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Siod\u0142o ma ogromny wp\u0142yw na komfort jazdy. W\u0142a\u015bnie dlatego ma odpowiednie dla dzieci w wieku u\u017cytkownik\u00f3w rozmiary i kszta\u0142t, aby idealnie pasowa\u0142o do miednicy u\u017cytkownik\u00f3w woom GO, zapewniaj\u0105c maksymaln\u0105 wygod\u0119 podczas jazdy oraz efektywno\u015b\u0107 peda\u0142owania. Teraz Twoje dziecko mo\u017ce czerpa\u0107 pe\u0142ni\u0119 rado\u015bci z ka\u017cdej chwili jazdy!<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Uniwersalne opony<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wysok\u0105 jako\u015b\u0107 opon potwierdza ich lekko\u015b\u0107 i przyczepno\u015b\u0107 bie\u017cnika. Z oryginalnymi oponami, na woom GO 2 dziecko mo\u017ce jecha\u0107 bez wysi\u0142ku po ka\u017cdej nawierzchni. Z \u0142atwo\u015bci\u0105 pokona \u017cwir, asfalt i teren. Jest bezpieczne je\u017cd\u017c\u0105c na wprost lub pokonuj\u0105c zakr\u0119ty i to bez wzgl\u0119du na sw\u00f3j temperament. A odblaskowy pasek umieszczony na boku opony jest znakomicie widoczny w \u015bwietle reflektor\u00f3w.<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Sprytnie zaprojektowane ko\u0142a<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">woom GO 2 ma wysokiej jako\u015bci ko\u0142a, dopracowane w najmniejszym szczeg\u00f3le \u2013 od lekko tocz\u0105cych si\u0119 piast, przez wytrzyma\u0142e szprychy ze stali nierdzewnej, a\u017c po lekkie aluminiowe obr\u0119cze. Lekko, \u0142atwo i przyjemnie!<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kompaktowa os\u0142ona \u0142a\u0144cucha<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Pe\u0142na os\u0142ona \u0142a\u0144cucha jest jednocze\u015bnie kompaktowa, solidna i stylowa. Skutecznie chroni dziecko przed urazami, a nogawki przed zabrudzeniami. Plamy ze smaru? A co to takiego?<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Ergonomiczne korby<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wysok\u0105 jako\u015b\u0107 korb podkre\u015bla ich precyzyjnie dobrana d\u0142ugo\u015b\u0107 oraz odst\u0119p mi\u0119dzy peda\u0142ami, idealnie dopasowane do anatomii dziecka. Dzi\u0119ki temu zapewniaj\u0105 optymaln\u0105 postaw\u0119 i naturalne ruchy. Peda\u0142owanie? Bu\u0142ka z mas\u0142em!<\/p>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>\u0141atwo\u015b\u0107 dopasowania roweru \u2013 kierownica i sztyca<\/b><\/li>\n<\/ul>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Oznaczenia ABC na kierownicy i sztycy s\u0105 przewodnikiem do \u0142atwej oraz precyzyjnej regulacji woom GO 2, dzi\u0119ki czemu rower mo\u017ce rosn\u0105\u0107 razem z Twoim dzieckiem. Wystarczy ustawi\u0107 siode\u0142ko tak, aby dziecko mog\u0142o dotyka\u0107 stopami pod\u0142o\u017ca i wygodnie peda\u0142owa\u0107. W kolejnym kroku dopasuj oznaczenie na kierownicy zgodnie z oznaczeniem na sztycy \u2013 i gotowe!<\/p>\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">woom GO 2<\/p>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Specyfikacja<\/h3>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Rama<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekka, wysokiej jako\u015bci rama wykonana z aluminium AA 6061<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ko\u0142a 14\u201d<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">\u0141atwo\u015b\u0107 prowadzenia: niski przekrok, bardzo niska pozycja jad\u0105cego dziecka, d\u0142ugi rozstaw osi i samosteruj\u0105ca geometria przedniego ko\u0142a zapewniaj\u0105 du\u017c\u0105 stabilno\u015b\u0107, dobry balans i wi\u0119cej rado\u015bci dla jad\u0105cego, a tak\u017ce spokoju g\u0142owy dla obserwuj\u0105cych popisy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Ko\u0142a<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultralekkie aluminiowe obr\u0119cze<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekkie aluminiowe piasty z uszczelnionymi \u0142o\u017cyskami<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Monta\u017c i demonta\u017c za pomoc\u0105 klucza imbusowego 5 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">16 lekkich, super mocnych stalowych szprych, zaplecionych na krzy\u017c<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Widelec<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekki aluminiowy widelec typu unicrown<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Rura sterowa 1\u201d<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ustawienie widelca wzgl\u0119dem ko\u0142a zapewnia du\u017c\u0105 samosterowno\u015b\u0107, u\u0142atwiaj\u0105c\u0105 bezpieczn\u0105 jazd\u0119<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Opony<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">14 \u00d7 1.4\u201d Schwalbe Little Joe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wyprodukowane zgodnie z \u201cdoros\u0142ymi\u201d technologiami maj\u0105 jako\u015b\u0107 wymagan\u0105 nawet przez specjalist\u00f3w, a wi\u0119c przy \u015bwietnej przyczepno\u015bci s\u0105 bardzo lekkie i maj\u0105 niskie opory toczenia \u2013 bardzo podnosi to poziom bezpiecze\u0144stwa przy minimalnym wysi\u0142ku<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Samochodowe wentyle umo\u017cliwiaj\u0105ce pompowanie opon nawet na stacjach benzynowych.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Odblaskowe paski zwi\u0119kszaj\u0105 widoczno\u015b\u0107 z boku<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Stery<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W pe\u0142ni zintegrowane stery 1\u201d<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Uszczelnione \u0142o\u017cyska maszynowe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zintegrowana obejma stabilizuj\u0105ca<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Stabilizator kierownicy<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Elastyczny gumowy pier\u015bcie\u0144 \u0142\u0105cz\u0105cy widelec z ram\u0105<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Stabilizuje kierowanie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zapobiega upadkom spowodowanym nadmiernym skr\u0119ceniem kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Mostek<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultralekki mostek z aluminium wzmocnionego kuciem<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">40 mm \/ +15\u00b0<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wpuszczona \u015bruba zaciskowa i zaokr\u0105glony kszta\u0142t \u2013 maksymalnie przyjazny dla kolan<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Kierownica przymocowana do mostka za pomoc\u0105 dw\u00f3ch \u015brub imbusowych 4 mm<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Siode\u0142ko<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczny i dopasowany do wieku u\u017cytkownika design<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wytrzyma\u0142y i odporny na warunki atmosferyczne materia\u0142 wierzchni<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Kierownica<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Szeroka, ergonomiczna i lekka kierownica z aluminium dla lepszej kontroli<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W stylu BMX z wysokim wznosem dla pe\u0142nej adaptacji do wzrostu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Oznaczenie ABC do precyzyjnej regulacji wysoko\u015bci siod\u0142a w stosunku do kierownicy.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Piaskowana i anodowana na czarno, wi\u0119c farba nie odpry\u015bnie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Cienki uchwyt, odpowiedni nawet dla bardzo ma\u0142ych d\u0142oni<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Szeroko\u015b\u0107: 500 mm<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Rura siod\u0142owa<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Anodowana aluminiowa rura siod\u0142owa, wi\u0119c farba nie odpry\u015bnie, z widoczn\u0105 lini\u0105 maksymalnego wysuni\u0119cia<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zintegrowany zestaw redukcyjny w rurze siod\u0142owej, zapobiegaj\u0105cy rysowaniu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Oznaczenie ABC dla \u0142atwej i precyzyjnej regulacji wysoko\u015bci siod\u0142a w stosunku do kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Chwyty<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczny kszta\u0142t<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ultra cienki, dostosowany \u015brednic\u0105 do dzieci\u0119cych d\u0142oni uchwyt, zapewniaj\u0105cy pewne trzymanie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Strefa komfortu, zapewniaj\u0105ca idealny kontakt d\u0142oni z kierownic\u0105<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Powi\u0119kszone ko\u0144c\u00f3wki dla ochrony d\u0142oni w razie upadku<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Chwyty typu lock-on, czyli ze skr\u0119can\u0105 \u015brubkami obejm\u0105, uniemo\u017cliwiaj\u0105c\u0105 obracanie si\u0119 nawet na mokrej kierownicy<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Zacisk rury siod\u0142owej<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wykonany z aluminium<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Eliminuje ryzyko skr\u0119cania i\/lub obracania<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Nap\u0119d<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Lekkie, kute aluminiowe korby o d\u0142ugo\u015bci 80 mm i w\u0105skim rozstawem (Q-factor) peda\u0142\u00f3w<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">18 z\u0119b\u00f3w z przodu i 10 z\u0119b\u00f3w z ty\u0142u<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">W\u0105skie, dzieci\u0119ce, p\u0142askie plastikowe peda\u0142y platformowe<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Uszczelniony wk\u0142ad suportu<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Brak hamulca torpedo \u2013 u\u0142atwia dziecku startowanie, bo zawsze mo\u017ce ustawi\u0107 peda\u0142 w wygodnej pozycji do ruszania<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Hamulce<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Dwa niezale\u017cnie dzia\u0142aj\u0105ce mini V-brake, wymagaj\u0105ce minimalnej si\u0142y do uzyskania maksymalnej si\u0142y hamowania.<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Ergonomiczna klamka hamulca zaprojektowana z my\u015bl\u0105 o ma\u0142ych d\u0142oniach, kr\u00f3tkich palcach i niewielkiej sile<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Wysokiej jako\u015bci linki hamulcowe Jagwire o niskim wsp\u00f3\u0142czynniku tarcia, zapewniaj\u0105ce lekkie i p\u0142ynne dzia\u0142anie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">Zielona klamka hamulca i klocki hamulcowe, dla identyfikacji wizualnej tylnego hamulca<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Waga<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">5 kg (bez peda\u0142\u00f3w)<\/li>\n<\/ul>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Limit obci\u0105\u017cenia<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">60 kg<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1279px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom\" srcset=\"https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom 360w,https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom 720w,https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom 1024w,https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom 1440w,https:\/\/a.allegroimg.com\/original\/117cb9\/a35371924dbfbddf51acc436e6f5\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Marka-Woom 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Marka Woom\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski\" srcset=\"https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski 360w,https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski 720w,https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski 1024w,https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski 1440w,https:\/\/a.allegroimg.com\/original\/111a4c\/6dc7405c43dd8ba98e004e9863c2\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski 1920w\" sizes=\"100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2\" srcset=\"https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2 360w,https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2 720w,https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2 1024w,https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2 1440w,https:\/\/a.allegroimg.com\/original\/112db2\/a564716448d29d944ab9d584de26\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Model-go-2 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Model go 2\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza\" srcset=\"https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza 360w,https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza 720w,https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza 1024w,https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza 1440w,https:\/\/a.allegroimg.com\/original\/11ed3f\/90df07b0431f937385247ba444af\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-ramy-mniejsza 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Rozmiar ramy mniejsza\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1357px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14\" srcset=\"https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14 360w,https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14 720w,https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14 1024w,https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14 1440w,https:\/\/a.allegroimg.com\/original\/11e4ad\/b84ccd39429a91d3c239cadc8dcf\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Rozmiar-kola-14 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Rozmiar ko\u0142a (&quot;) 14\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks\" srcset=\"https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks 360w,https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks 720w,https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks 1024w,https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks 1440w,https:\/\/a.allegroimg.com\/original\/115874\/c80a796e4221a697a499ba736a32\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Plec-produkt-uniseks 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski P\u0142e\u0107 produkt uniseks\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743\" srcset=\"https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743 360w,https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743 720w,https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743 1024w,https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743 1440w,https:\/\/a.allegroimg.com\/original\/113e1b\/801cc7294c1184f001e789059e9c\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kod-producenta-9120083728743 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Kod producenta 9120083728743\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1920px;max-height:1280px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski\" srcset=\"https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski 360w,https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski 720w,https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski 1024w,https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski 1440w,https:\/\/a.allegroimg.com\/original\/11c858\/b38dbe75437a8ca61d15adfe5529\/Lekki-Rower-dla-dziecka-Woom-GO-2-14-Metallic-Blue-Niebieski-Kolor-niebieski 1920w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"1920px\" alt=\"Lekki Rower dla dziecka Woom GO 2 14&amp;quot; Metallic Blue\/Niebieski Kolor niebieski\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>ROWER DLA DZIECI WOOM GO 2<\/p>\n<p>Ultralekki rower na 14&quot; ko\u0142ach stworzony z my\u015bl\u0105 o pierwszych, bezpiecznych obrotach peda\u0142ami, przeznaczony dla dzieci w wieku 3 lat i starszych.<\/p>\n<p>Rozmiar:&nbsp;14&quot;<\/p>\n<p>Waga:&nbsp;5 kg<\/p>\n<p>Wiek:&nbsp;3 &#8211; 4.5 lat<\/p>\n<p>Wzrost:&nbsp;95\u2013110 cm<\/p>\n<p>Rower woom GO 2<\/p>\n<p>Nadchodzi magiczny moment!<\/p>\n","protected":false},"featured_media":14557,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[705],"product_cat":[728,688,730,687],"product_tag":[],"class_list":{"0":"post-14556","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-woom","7":"product_cat-mtb-gorskie","8":"product_cat-rowery","9":"product_cat-rowery-dh","10":"product_cat-rowery-i-akcesoria","12":"first","13":"instock","14":"sale","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556.jpg",1920,1280,false],"thumbnail":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-150x150.jpg",150,150,true],"medium":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-300x200.jpg",300,200,true],"medium_large":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-768x512.jpg",768,512,true],"large":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556.jpg",1920,1280,false],"woocommerce_thumbnail":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-600x400.jpg",600,400,true],"woocommerce_gallery_thumbnail":["https:\/\/velravo.shop\/ro64\/wp-content\/uploads\/2026\/02\/allegro-image-14556-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/velravo.shop\/ro64\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"ROWER DLA DZIECI WOOM GO 2 Ultralekki rower na 14&quot; ko\u0142ach stworzony z my\u015bl\u0105 o pierwszych, bezpiecznych obrotach peda\u0142ami, przeznaczony dla dzieci w wieku 3 lat i starszych. Rozmiar:&nbsp;14&quot; Waga:&nbsp;5 kg Wiek:&nbsp;3 - 4.5 lat Wzrost:&nbsp;95\u2013110 cm Rower woom GO 2 Nadchodzi magiczny moment!","_links":{"self":[{"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/product\/14556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/media\/14557"}],"wp:attachment":[{"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/media?parent=14556"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/product_brand?post=14556"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/product_cat?post=14556"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/velravo.shop\/ro64\/wp-json\/wp\/v2\/product_tag?post=14556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}